{"id":20032,"date":"2022-04-20T13:28:45","date_gmt":"2022-04-20T11:28:45","guid":{"rendered":"https:\/\/www.ameol.it\/dsgvo-ame\/"},"modified":"2024-05-16T15:09:10","modified_gmt":"2024-05-16T13:09:10","slug":"dsgvo-ame","status":"publish","type":"page","link":"https:\/\/www.ameol.it\/de\/dsgvo-ame\/","title":{"rendered":"DSGVO AME"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"20032\" class=\"elementor elementor-20032 elementor-3881\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-00fb933 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00fb933\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f57fc63\" data-id=\"f57fc63\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9422f04 elementor-widget elementor-widget-heading\" data-id=\"9422f04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informationen \u00fcber die Verarbeitung personenbezogener Daten gem\u00e4\u00df Artikel 13, 14 der Verordnung (EU) 2016\/679 \u00fcber den Schutz personenbezogener Daten (DSGVO)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcac20c elementor-widget elementor-widget-text-editor\" data-id=\"dcac20c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In \u00dcbereinstimmung mit den Bestimmungen der Verordnung (EU) 2016\/679 (in der Folge \u201eDSGVO\u201c genannt) wird auf dieser Seite beschrieben, wie wir die personenbezogenen Daten von Nutzern verarbeiten, die unsere Website besuchen oder unsere Dienste in Anspruch nehmen. Bevor Sie uns personenbezogene Daten mitteilen, bitten wir Sie daher, die folgenden Informationen aufmerksam zu lesen, da sie wichtige Informationen zum Schutz Ihrer personenbezogenen Daten enthalten.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bd6f9c elementor-widget elementor-widget-text-editor\" data-id=\"3bd6f9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diese Datenschutz- und Cookie-Richtlinie:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c203347 elementor-widget elementor-widget-text-editor\" data-id=\"c203347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>ist f\u00fcr die Website ameol.it bestimmt, einschlie\u00dflich der speziellen Bereiche, in denen der Benutzer frei und ausdr\u00fccklich eine Reihe von ihn betreffenden Daten angeben kann, um mit dem Unternehmen Advanced Microwave Engineering S.r.l. in Kontakt zu treten oder Anfragen zu senden;<\/li>\n<li>beschreibt die Modalit\u00e4ten der Nutzung, der Weitergabe, des Zugriffs, der \u00c4nderung oder der L\u00f6schung der vom Benutzer bereitgestellten pers\u00f6nlichen Daten.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ede55f elementor-widget elementor-widget-text-editor\" data-id=\"5ede55f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diese Datenschutz- und Cookie-Richtlinie gilt nur f\u00fcr diese Website und nicht f\u00fcr andere Websites, die der Benutzer \u00fcber auf den Seiten dieser Website angegebenen Links aufrufen kann. Wenn Sie andere Websites besuchen, empfehlen wir Ihnen, die jeweiligen Datenschutz- und Cookie-Richtlinien zu lesen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68d1596 elementor-widget elementor-widget-text-editor\" data-id=\"68d1596\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die f\u00fcr diese Website geltenden Sicherheitsma\u00dfnahmen wurden festgelegt und entwickelt, um zu gew\u00e4hrleisten, dass die personenbezogenen Daten der Nutzer gem\u00e4\u00df den Grunds\u00e4tzen der Rechtm\u00e4\u00dfigkeit, Korrektheit, Transparenz, Beschr\u00e4nkung der Zwecke und der Aufbewahrung, Datenminimierung, Genauigkeit, Integrit\u00e4t und Vertraulichkeit und in \u00dcbereinstimmung mit den geltenden nationalen und europ\u00e4ischen Vorschriften verarbeitet werden. Advanced Microwave Engineering S.r.l. beh\u00e4lt sich das Recht vor, den Inhalt dieser Datenschutz- und Cookie-Richtlinie ganz oder teilweise zu \u00e4ndern oder einfach zu aktualisieren, und zwar auch aufgrund von \u00c4nderungen der anwendbaren Gesetzgebung oder aufgrund von Hinweisen der italienischen Datenschutzbeh\u00f6rde. Die Nutzer der Website www.ameol.it werden daher gebeten, diesen Abschnitt regelm\u00e4\u00dfig zu besuchen, um \u00fcber die erhobenen Daten und deren Verwendung durch den f\u00fcr die Verarbeitung Verantwortlichen stets auf dem aktuellen Stand zu sein.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4298f63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4298f63\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bdd38f3\" data-id=\"bdd38f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2338dfa elementor-widget elementor-widget-heading\" data-id=\"2338dfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1. Identit\u00e4t und Kontaktangaben des f\u00fcr die Datenverarbeitung Verantwortlichen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c92070 elementor-widget elementor-widget-text-editor\" data-id=\"8c92070\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der f\u00fcr die Datenverarbeitung Verantwortliche ist das Unternehmen Advanced Microwave Engineering S.r.l. (abgek\u00fcrzt A.M.E. Srl), mit Sitz in Via Lucca, 44 50142 Florenz (FI) St.-Nr.\/USt-ID Nr. 05016620485. A.M.E. Srl kann bei allen Fragen zur Verarbeitung personenbezogener Daten per E-Mail an privacy@ameol.it kontaktiert werden.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f7c311 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f7c311\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a35b26\" data-id=\"9a35b26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db5e28b elementor-widget elementor-widget-heading\" data-id=\"db5e28b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2. Arten von verarbeiteten Daten<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b0a335 elementor-widget elementor-widget-heading\" data-id=\"5b0a335\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">2.1 Navigationsdaten<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13843aa elementor-widget elementor-widget-text-editor\" data-id=\"13843aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die f\u00fcr den Betrieb der Website verwendeten Computersysteme und Softwareverfahren erfassen w\u00e4hrend ihres normalen Betriebs einige personenbezogene Daten, deren \u00dcbermittlung durch die Verwendung von Internet-Kommunikationsprotokollen vorgesehen ist. Diese Daten werden nicht gesammelt, um sie identifizierten Interessenten zuzuordnen, aber sie k\u00f6nnten aufgrund ihrer Beschaffenheit durch Verarbeitung und Verkn\u00fcpfung mit Daten im Besitz von Dritten die Identifizierung der Nutzer erm\u00f6glichen. Zu dieser Datenkategorie geh\u00f6ren die IP-Adressen oder Dom\u00e4nennamen der von den Nutzern verwendeten Computer, die sich mit der Website verbinden, die URI (Uniform Resource Identifier)-Notationsadressen der angeforderten Ressourcen, die Uhrzeit der Anfrage, die f\u00fcr die \u00dcbermittlung der Anfrage an den Server verwendete Methode, die Gr\u00f6\u00dfe der als Antwort erhaltenen Datei, der Zahlencode, der den Status der vom Server gegebenen Antwort angibt (erfolgreich, Fehler usw.) sowie andere Parameter, die sich auf das Betriebssystem und die IT-Umgebung des Nutzers beziehen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b8cc2a elementor-widget elementor-widget-heading\" data-id=\"7b8cc2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">2.2 Freiwillig von den Nutzern zur Verf\u00fcgung gestellte Daten<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7acd3c elementor-widget elementor-widget-text-editor\" data-id=\"a7acd3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das fakultative, ausdr\u00fcckliche und absichtliche Versenden von E-Mail-Nachrichten an die auf der Website angegebenen Adressen sowie das fakultative, ausdr\u00fcckliche und absichtliche Ausf\u00fcllen von Kontaktformularen auf der Website f\u00fchren zur Erfassung der Adresse des Absenders, die f\u00fcr die Beantwortung der Anfragen erforderlich ist, sowie anderer personenbezogener Daten, die freiwillig in die E-Mail- und Kontaktformulare geschrieben werden.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3784a8 elementor-widget elementor-widget-heading\" data-id=\"a3784a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">2.3 Cookies<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84d0638 elementor-widget elementor-widget-text-editor\" data-id=\"84d0638\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cookies sind Textdateien, die kleine Mengen an Informationen enthalten und auf dem Ger\u00e4t des Nutzers gespeichert werden, wenn dieser eine Website besucht.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55c4244 elementor-widget elementor-widget-text-editor\" data-id=\"55c4244\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Beim Surfen auf der Website www.ameol.it werden automatisch Cookies heruntergeladen, die f\u00fcr das Surfen auf der Website erforderlich sind, n\u00e4mlich: technische Cookies, die f\u00fcr eine optimale Navigation auf der Website erforderlich sind, und Tracking-Cookies mit anonymisierten Informationen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39d3b51 elementor-widget elementor-widget-text-editor\" data-id=\"39d3b51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Andere Arten von Cookies, die f\u00fcr das Surfen nicht erforderlich sind, k\u00f6nnen ebenfalls heruntergeladen werden, sofern der Nutzer dies ausdr\u00fccklich und freiwillig \u00fcber das Cookie-Banner akzeptiert. Diese Cookies k\u00f6nnen statistische, profilbildende Zwecke oder Marketingzwecke haben.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-995c08e elementor-widget elementor-widget-text-editor\" data-id=\"995c08e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die vollst\u00e4ndige und aktualisierte Liste der Cookie-Typen ist im Banner des Tools zur Erkennung und Verwaltung der Cookies verf\u00fcgbar.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d12c033 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d12c033\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c279047\" data-id=\"c279047\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26e8026 elementor-widget elementor-widget-heading\" data-id=\"26e8026\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3. Zweck und Rechtsgrundlage der Verarbeitung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7bc982 elementor-widget elementor-widget-heading\" data-id=\"f7bc982\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">3.1 Navigationsdaten<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d85f7b elementor-widget elementor-widget-text-editor\" data-id=\"0d85f7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die f\u00fcr die Nutzung der Website erforderlichen Navigationsdaten werden auch verwendet, um anonyme statistische Informationen \u00fcber die Nutzung der Website zu erhalten und ihr ordnungsgem\u00e4\u00dfes Funktionieren zu \u00fcberpr\u00fcfen. Die Daten k\u00f6nnten verwendet werden, um die Verantwortlichkeit im Falle hypothetischer Computerstraftaten gegen die Website zu ermitteln.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd5b0da elementor-widget elementor-widget-text-editor\" data-id=\"cd5b0da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Konkret k\u00f6nnen die Navigationsdaten aller Besucher und Nutzer der Website f\u00fcr Folgendes verwendet werden:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7090471 elementor-widget elementor-widget-text-editor\" data-id=\"7090471\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\r\n \t<li>um die Navigation durch die \u00f6ffentlichen Seiten der Website zu erm\u00f6glichen;<\/li>\r\n \t<li>um anonyme statistische Informationen \u00fcber die Nutzung der Website zu erhalten (z.B. Analyse der meistbesuchten Seiten);<\/li>\r\n \t<li>um anonyme statistische Informationen \u00fcber geografische Herkunftsgebiete zu erhalten\r\num das ordnungsgem\u00e4\u00dfe Funktionieren der Website zu \u00fcberwachen;<\/li>\r\n \t<li>um die m\u00f6gliche Haftung im Falle von Verst\u00f6\u00dfen zum Nachteil der Website feststellen zu k\u00f6nnen.<\/li>\r\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01c9b01 elementor-widget elementor-widget-text-editor\" data-id=\"01c9b01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Rechtsgrundlagen f\u00fcr diese Verarbeitung sind das berechtigte Interesse des f\u00fcr die Verarbeitung Verantwortlichen und die Einhaltung rechtlicher Verpflichtungen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20aabd0 elementor-widget elementor-widget-heading\" data-id=\"20aabd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">3.2 Freiwillig von den Nutzern zur Verf\u00fcgung gestellte Daten<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af0d0d1 elementor-widget elementor-widget-text-editor\" data-id=\"af0d0d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Zwecke, f\u00fcr die diese Daten verwendet werden oder verwendet werden k\u00f6nnen, sowie die spezifischen Verarbeitungsmethoden sind auf den Seiten der Website, die die Kontaktformulare enthalten, angegeben. F\u00fcr die Verarbeitung auf der Grundlage einer Einwilligung holt A.M.E. S.r.l. die ausdr\u00fcckliche vorherige Zustimmung des Nutzers ein.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24f77d5 elementor-widget elementor-widget-text-editor\" data-id=\"24f77d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die durch E-Mail-Nachrichten \u00fcbermittelten Daten, einschlie\u00dflich der Adressen, von denen aus die Nachrichten \u00fcbermittelt wurden, werden ausschlie\u00dflich zur Beantwortung der Anfragen der Nutzer verarbeitet.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b63091 elementor-widget elementor-widget-text-editor\" data-id=\"0b63091\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die personenbezogenen Daten, die die Nutzer freiwillig zur Verf\u00fcgung stellen, werden insbesondere f\u00fcr die folgenden Zwecke verarbeitet:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-92d9fc5 elementor-widget elementor-widget-text-editor\" data-id=\"92d9fc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li>um per E-Mail eingegangene Informationsanfragen zu Produkten und Dienstleistungen von A.M.E. Srl zu beantworten;<\/li>\n<li>um es Ihnen zu erm\u00f6glichen, Informationsmaterial \u00fcber die von A.M.E. Srl angebotenen Produkte und Dienstleistungen einzusehen;<\/li>\n<li>um interessierten Personen das Abonnieren von Newslettern zu erm\u00f6glichen;<\/li>\n<li>um interessierten Personen das Herunterladen der Brosch\u00fcre \u00fcber Produkte\/Dienstleistungen von A.M.E. Srl. zu erm\u00f6glichen.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a9aabe elementor-widget elementor-widget-text-editor\" data-id=\"2a9aabe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Rechtsgrundlage f\u00fcr diese Verarbeitung ist das berechtigte Interesse des f\u00fcr die Verarbeitung Verantwortlichen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28601e8 elementor-widget elementor-widget-text-editor\" data-id=\"28601e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vorbehaltlich der vorherigen Zustimmung k\u00f6nnen die Daten auch f\u00fcr folgende Zwecke verarbeitet werden:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-175d7c3 elementor-widget elementor-widget-text-editor\" data-id=\"175d7c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\r\n \t<li>kommerzielle Zwecke und direktes und indirektes Marketing;<\/li>\r\n \t<li>Profilerstellung im Zusammenhang mit dem Bezugsgesch\u00e4ftsbereich von A.M.E. Srl.<\/li>\r\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d7a648 elementor-widget elementor-widget-text-editor\" data-id=\"2d7a648\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bitte beachten Sie, dass die von A.M.E. s.r.l. ausgef\u00fchrten Direktmarketing-Aktivit\u00e4ten die Erhebung und Verwendung von sachdienlichen und auf das Notwendige beschr\u00e4nkten Daten in Bezug auf den Zweck, f\u00fcr den sie verarbeitet werden, f\u00fcr die Erstellung von Studien, Untersuchungen, Marktstatistiken, die Zusendung von Werbe- und Informationsmaterial, die Durchf\u00fchrung von Direktverkaufsaktivit\u00e4ten oder die Platzierung von Produkten oder Dienstleistungen, die Zusendung von kommerziellen Informationen und die Durchf\u00fchrung interaktiver kommerzieller Kommunikationen dienen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da875c2 elementor-widget elementor-widget-text-editor\" data-id=\"da875c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Profiling hingegen besteht aus der Sammlung von Informationen \u00fcber das Verhalten und die Gesch\u00e4ftsgewohnheiten in dem betreffenden T\u00e4tigkeitsbereich, um die angebotenen Dienstleistungen entsprechend den Bed\u00fcrfnissen der Kunden, die ihre ausdr\u00fcckliche Zustimmung erteilt haben, zu verbessern.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aea5097 elementor-widget elementor-widget-text-editor\" data-id=\"aea5097\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In Bezug auf Marketing- und Profiling-Aktivit\u00e4ten weisen wir darauf hin, dass diese Aktivit\u00e4ten nicht durchgef\u00fchrt werden k\u00f6nnen, wenn Sie der Verarbeitung nicht ausdr\u00fccklich zustimmen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b375df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b375df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d374b4a\" data-id=\"d374b4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d185c67 elementor-widget elementor-widget-heading\" data-id=\"d185c67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4. Freiwillige Bereitstellung von Daten<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c04a878 elementor-widget elementor-widget-text-editor\" data-id=\"c04a878\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abgesehen von den Angaben zu den Navigationsdaten steht es den Nutzern frei, ihre personenbezogenen Daten anzugeben oder nicht. Die mangelnde Bereitstellung der Daten \u00fcber das Kontaktformular oder per E-Mail kann dazu f\u00fchren, dass Sie die angeforderten Informationen nicht erhalten k\u00f6nnen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-574b1d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"574b1d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4121e68\" data-id=\"4121e68\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af546f7 elementor-widget elementor-widget-heading\" data-id=\"af546f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5. Dauer der Datenaufbewahrung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26d7b59 elementor-widget elementor-widget-text-editor\" data-id=\"26d7b59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir bewahren Ihre Daten so lange auf, wie es zur Erf\u00fcllung des Zwecks, f\u00fcr den sie erhoben wurden, erforderlich ist.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29d494f elementor-widget elementor-widget-text-editor\" data-id=\"29d494f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Sie ein Konto erstellen, bewahren wir Ihre Daten so lange auf, wie Ihr Konto aktiv ist. Auch nach der Schlie\u00dfung Ihres Kontos werden wir die Daten aufbewahren, soweit dies erforderlich ist, um unseren gesetzlichen Verpflichtungen nachzukommen, unsere Rechte zu sch\u00fctzen, Betrug zu verhindern oder diese Datenschutzrichtlinie umzusetzen. Unter besonderer Ber\u00fccksichtigung des Schutzes unserer Rechte legen wir fest, dass wir eine Aufbewahrungsfrist f\u00fcr personenbezogene Daten von zehn Jahren ab der Schlie\u00dfung des Kontos festlegen, die sich auf die zehnj\u00e4hrige Verj\u00e4hrungsfrist gem\u00e4\u00df Artikel 2946 des it. Zivilgesetzbuchs st\u00fctzt.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66cb4b0 elementor-widget elementor-widget-text-editor\" data-id=\"66cb4b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Im Einzelnen werden die Daten f\u00fcr folgende Zeitr\u00e4ume aufbewahrt:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d0a80a elementor-widget elementor-widget-text-editor\" data-id=\"5d0a80a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\r\n \t<li>Daten, die erhoben wurden, um auf per E-Mail eingegangene Informationsanfragen zu Produkten und Dienstleistungen von A.M.E. zu antworten: 2 Jahre ab dem letzten Vertrag;<\/li>\r\n \t<li>Daten, die erhoben wurden, um es Ihnen zu erm\u00f6glichen, Informationsmaterial \u00fcber die von A.M.E. Srl angebotenen Produkte und Dienstleistungen einzusehen: 2 Jahre ab dem letzten Vertrag;<\/li>\r\n \t<li>Daten, die erhoben werden, um interessierten Personen das Abonnieren von Newslettern zu erm\u00f6glichen: Das Abonnement f\u00fcr die neuen Newsletters bleibt so lange aktiv, bis die interessierte Person die Stornierung beantragt, die Daten werden dann ab dem Datum des Stornierungsantrags 2 Jahre lang aufbewahrt;<\/li>\r\n \t<li>Daten, die gesammelt werden, um interessierten Personen die M\u00f6glichkeit zu geben, die Brosch\u00fcre der Produkte\/Dienstleistungen von A.M.E. Srl herunterzuladen: 2 Jahre ab dem letzten Vertrag;<\/li>\r\n \t<li>Daten, die mit der Zustimmung der betroffenen Person zu Marketingzwecken erhoben wurden: bis zum Widerruf der Zustimmung;<\/li>\r\n \t<li>Daten, die mit Zustimmung der betroffenen Person f\u00fcr Profilingzwecke gesammelt wurden: bis zum Widerruf der Zustimmung.<\/li>\r\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7293df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7293df\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e10ddd4\" data-id=\"e10ddd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7e0089 elementor-widget elementor-widget-heading\" data-id=\"f7e0089\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6. Weitergabe von Daten<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae77be6 elementor-widget elementor-widget-text-editor\" data-id=\"ae77be6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A.M.E. Srl gibt keine personenbezogenen Daten an Drittl\u00e4nder oder internationale Organisationen weiter. AME Srl beh\u00e4lt sich jedoch das Recht vor, Cloud-Dienste zu nutzen. In diesem Fall werden die Dienstleister unter denjenigen ausgew\u00e4hlt, die angemessene Garantien bieten, wie in Art. 46 der DSGVO vorgesehen. Die Verarbeitung erfolgt also nach einer der Methoden, die nach den geltenden Rechtsvorschriften zul\u00e4ssig sind.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68c59a6 elementor-widget elementor-widget-text-editor\" data-id=\"68c59a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Au\u00dferdem beh\u00e4lt sich AME Srl das Recht vor, die Daten an die Tochtergesellschaft A.M.E. DEUTSCHLAND GmbH zu \u00fcbermitteln.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cbd02a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cbd02a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e4f1baf\" data-id=\"e4f1baf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8f6da8 elementor-widget elementor-widget-heading\" data-id=\"d8f6da8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">7. Empf\u00e4nger oder m\u00f6gliche Kategorien von Empf\u00e4ngern der personenbezogenen Daten<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad44052 elementor-widget elementor-widget-text-editor\" data-id=\"ad44052\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Verarbeitung der Daten der betroffenen Person erfolgt durch das interne Personal des Verantwortlichen f\u00fcr die Datenverarbeitung (Angestellte oder Mitarbeiter), die gem\u00e4\u00df den geltenden Datenschutz- und Datensicherheitsbestimmungen identifiziert und befugt sind, die Daten gem\u00e4\u00df den erteilten Anweisungen und Aufgaben zu verarbeiten.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eb57d3 elementor-widget elementor-widget-text-editor\" data-id=\"2eb57d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Daten werden nicht weitergegeben.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1334ed4 elementor-widget elementor-widget-text-editor\" data-id=\"1334ed4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sollte sich dies f\u00fcr die in Artikel 3 genannten Zwecke als notwendig erweisen, k\u00f6nnen die Daten an Dritte weitergegeben werden, die sie je nach Fall als (gem\u00e4\u00df Artikel 28 der DSGVO eigens beauftragte) Datenverarbeiter oder als \u201eeigenst\u00e4ndige\u201c Datenverantwortliche verarbeiten. Im Einzelnen k\u00f6nnen personenbezogene Daten verarbeitet werden von:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f30254 elementor-widget elementor-widget-text-editor\" data-id=\"3f30254\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\r\n \t<li>Fachleuten, Gesellschaften, Verb\u00e4nden oder Fachfirmen, die den Verantwortlichen f\u00fcr die Datenverarbeitung zu Marketing-, Handels- oder Rechtsschutzzwecken unterst\u00fctzen oder beraten;<\/li>\r\n \t<li>allen gesetzlich vorgesehenen \u00f6ffentlichen Einrichtungen, der Polizei oder den Organen der \u00f6ffentlichen Sicherheit oder anderen \u00f6ffentlichen Stellen zum Schutz der \u00f6ffentlichen Ordnung und Sicherheit, zur Verh\u00fctung, Untersuchung oder Verfolgung von Straftaten;<\/li>\r\n \t<li>Unternehmen und Fachleuten, die Dienstleistungen im Bereich der elektronischen Datenverarbeitung, Software und IT-Beratung sowie der Verwaltung von Informationsdiensten anbieten.<\/li>\r\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e31de17 elementor-widget elementor-widget-text-editor\" data-id=\"e31de17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Auf die personenbezogenen Daten der Nutzer der Website k\u00f6nnen auch Personen zugreifen, die in ihrer Eigenschaft als Datenverarbeiter Hilfs- und Beratungsdienste f\u00fcr die Verwaltung und Pflege der Website selbst und ganz allgemein professionelle Dienstleistungen verschiedener Art erbringen. Die Liste dieser verantwortlichen Personen kann beim Verantwortlichen \u00fcber die in Absatz 1 angegebene E-Mail-Adresse angefordert werden.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7daa31e elementor-widget elementor-widget-text-editor\" data-id=\"7daa31e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Daten der Nutzer k\u00f6nnen auch weitergegeben werden an:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c225be6 elementor-widget elementor-widget-text-editor\" data-id=\"c225be6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\r\n \t<li>Personen, die von A.M.E. S.r.l. zur Verarbeitung personenbezogener Daten f\u00fcr T\u00e4tigkeiten, die in engem Zusammenhang mit der Bereitstellung von Produkten\/Dienstleistungen oder Informationen stehen, erm\u00e4chtigt sind und die einer angemessenen gesetzlichen Geheimhaltungspflicht unterliegen;<\/li>\r\n \t<li>die Polizei, die Streitkr\u00e4fte und andere \u00f6ffentliche Verwaltungen, um die von den Gesetzen, Verordnungen und der nationalen oder europ\u00e4ischen Gesetzgebung vorgesehenen Verpflichtungen zu erf\u00fcllen, sowie Agenturen oder Fachleute, um die Verteidigung von A.M.E. S.r.l. vor Gericht zu erm\u00f6glichen, zum Beispiel im Falle von Verst\u00f6\u00dfen gegen das Netz durch die Nutzer.<\/li>\r\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14768bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14768bb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d4c2c8\" data-id=\"4d4c2c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d201311 elementor-widget elementor-widget-heading\" data-id=\"d201311\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">8. Profiling von Daten<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5e7f0f elementor-widget elementor-widget-text-editor\" data-id=\"e5e7f0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Daten, die sich aus dem Ausf\u00fcllen der Kontaktformulare auf der Website ergeben, k\u00f6nnen einem Profiling unterzogen werden, insbesondere um pers\u00f6nliche Aspekte der Nutzer in Bezug auf pers\u00f6nliche Vorlieben, Interessen, Verhalten oder Standorte zu analysieren oder vorauszusehen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb4318d elementor-widget elementor-widget-text-editor\" data-id=\"bb4318d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Verarbeitung solcher Daten, die gem\u00e4\u00df Artikel 9 der DSGVO ausschlie\u00dflich von \u201ebesonderer\u201c Art sind, ist nur mit einer jederzeit widerrufbaren Einwilligung m\u00f6glich.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b28de98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b28de98\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46bb029\" data-id=\"46bb029\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf769e9 elementor-widget elementor-widget-heading\" data-id=\"bf769e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">9. Rechte der betroffenen Person<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b1bcf2 elementor-widget elementor-widget-text-editor\" data-id=\"6b1bcf2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In Ihrer Eigenschaft als betroffene Person und in Bezug auf die in diesem Informationsblatt beschriebenen Verarbeitungen k\u00f6nnen Sie die in den Artikeln 7, von 15 bis 21 und 77 der Datenschutz-Grundverordnung (Recht auf Auskunft, Berichtigung, L\u00f6schung, Einschr\u00e4nkung der Verarbeitung, Recht auf Daten\u00fcbertragbarkeit, Widerspruchsrecht, Widerrufsrecht, Beschwerderecht) genannten Rechte aus\u00fcben. Sie k\u00f6nnen Ihre Rechte jederzeit aus\u00fcben, indem Sie an die E-Mail-Adresse privacy@ameol.it schreiben oder einen eingeschriebenen Brief an die folgende Adresse senden: A.M.E. Srl Via Lucca, 44 50142 Firenze (FI).<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4b543b elementor-widget elementor-widget-text-editor\" data-id=\"b4b543b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Aus\u00fcbung der Rechte ist gem\u00e4\u00df Artikel 12 der DSGVO kostenlos. Bei offensichtlich unbegr\u00fcndeten oder \u00fcberm\u00e4\u00dfigen Antr\u00e4gen, auch aufgrund von Wiederholungen, kann der f\u00fcr die Verarbeitung Verantwortliche Ihnen jedoch eine angemessene Geb\u00fchr in Rechnung stellen, die sich an den Verwaltungskosten f\u00fcr die Bearbeitung Ihres Antrags orientiert, oder er kann die Erf\u00fcllung Ihres Antrags verweigern.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9c485b elementor-widget elementor-widget-text-editor\" data-id=\"b9c485b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Antr\u00e4ge auf Aus\u00fcbung Ihrer Rechte werden ohne unangemessene Verz\u00f6gerung und in jedem Fall innerhalb eines Monats nach Antragstellung bearbeitet, nur in besonders komplexen F\u00e4llen und einer gro\u00dfen Anzahl von Antr\u00e4gen kann diese Frist um weitere 2 (zwei) Monate verl\u00e4ngert werden.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b21e0b8 elementor-widget elementor-widget-text-editor\" data-id=\"b21e0b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Interessierte Personen, die der Meinung sind, dass die Verarbeitung der sie betreffenden personenbezogenen Daten \u00fcber diese Website gegen die Bestimmungen der DSGVO verst\u00f6\u00dft, haben das Recht, eine Beschwerde beim Garant f\u00fcr den Schutz der pers\u00f6nlichen Daten (www.garanteprivacy.it) einzureichen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<!-- hidden section 20032-2e57081c -->\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Informationen \u00fcber die Verarbeitung personenbezogener Daten gem\u00e4\u00df Artikel 13, 14 der Verordnung (EU) 2016\/679 \u00fcber den Schutz personenbezogener Daten (DSGVO) In \u00dcbereinstimmung mit den Bestimmungen der Verordnung (EU) 2016\/679 (in der Folge \u201eDSGVO\u201c genannt) wird auf dieser Seite beschrieben, wie wir die personenbezogenen Daten von Nutzern verarbeiten, die unsere Website besuchen oder unsere Dienste in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":59,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-20032","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ameol.it\/de\/wp-json\/wp\/v2\/pages\/20032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ameol.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ameol.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ameol.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ameol.it\/de\/wp-json\/wp\/v2\/comments?post=20032"}],"version-history":[{"count":0,"href":"https:\/\/www.ameol.it\/de\/wp-json\/wp\/v2\/pages\/20032\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.ameol.it\/de\/wp-json\/wp\/v2\/media?parent=20032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}